{"id":2396,"count":1,"description":"","link":"https:\/\/www.wsisp.com\/helps\/tag\/kubernetes%e8%88%aa%e7%ba%bf%e5%9b%be%ef%bc%9a%e4%bb%8e%e8%88%b9%e9%95%bf%e5%88%b0k8s%e6%8e%8c%e8%88%b5%e8%80%85","name":"Kubernetes\u822a\u7ebf\u56fe\uff1a\u4ece\u8239\u957f\u5230K8s\u638c\u8235\u8005","slug":"kubernetes%e8%88%aa%e7%ba%bf%e5%9b%be%ef%bc%9a%e4%bb%8e%e8%88%b9%e9%95%bf%e5%88%b0k8s%e6%8e%8c%e8%88%b5%e8%80%85","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kubernetes\u822a\u7ebf\u56fe\uff1a\u4ece\u8239\u957f\u5230K8s\u638c\u8235\u8005\u5f52\u6863 - \u7f51\u7855\u4e92\u8054\u5e2e\u52a9\u4e2d\u5fc3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wsisp.com\/helps\/tag\/kubernetes\u822a\u7ebf\u56fe\uff1a\u4ece\u8239\u957f\u5230k8s\u638c\u8235\u8005\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kubernetes\u822a\u7ebf\u56fe\uff1a\u4ece\u8239\u957f\u5230K8s\u638c\u8235\u8005\u5f52\u6863 - \u7f51\u7855\u4e92\u8054\u5e2e\u52a9\u4e2d\u5fc3\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wsisp.com\/helps\/tag\/kubernetes\u822a\u7ebf\u56fe\uff1a\u4ece\u8239\u957f\u5230k8s\u638c\u8235\u8005\" \/>\n<meta property=\"og:site_name\" content=\"\u7f51\u7855\u4e92\u8054\u5e2e\u52a9\u4e2d\u5fc3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.wsisp.com\/helps\/tag\/kubernetes%e8%88%aa%e7%ba%bf%e5%9b%be%ef%bc%9a%e4%bb%8e%e8%88%b9%e9%95%bf%e5%88%b0k8s%e6%8e%8c%e8%88%b5%e8%80%85\",\"url\":\"https:\/\/www.wsisp.com\/helps\/tag\/kubernetes%e8%88%aa%e7%ba%bf%e5%9b%be%ef%bc%9a%e4%bb%8e%e8%88%b9%e9%95%bf%e5%88%b0k8s%e6%8e%8c%e8%88%b5%e8%80%85\",\"name\":\"Kubernetes\u822a\u7ebf\u56fe\uff1a\u4ece\u8239\u957f\u5230K8s\u638c\u8235\u8005\u5f52\u6863 - \u7f51\u7855\u4e92\u8054\u5e2e\u52a9\u4e2d\u5fc3\",\"isPartOf\":{\"@id\":\"https:\/\/www.wsisp.com\/helps\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.wsisp.com\/helps\/tag\/kubernetes%e8%88%aa%e7%ba%bf%e5%9b%be%ef%bc%9a%e4%bb%8e%e8%88%b9%e9%95%bf%e5%88%b0k8s%e6%8e%8c%e8%88%b5%e8%80%85#breadcrumb\"},\"inLanguage\":\"zh-Hans\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.wsisp.com\/helps\/tag\/kubernetes%e8%88%aa%e7%ba%bf%e5%9b%be%ef%bc%9a%e4%bb%8e%e8%88%b9%e9%95%bf%e5%88%b0k8s%e6%8e%8c%e8%88%b5%e8%80%85#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/www.wsisp.com\/helps\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kubernetes\u822a\u7ebf\u56fe\uff1a\u4ece\u8239\u957f\u5230K8s\u638c\u8235\u8005\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.wsisp.com\/helps\/#website\",\"url\":\"https:\/\/www.wsisp.com\/helps\/\",\"name\":\"\u7f51\u7855\u4e92\u8054\u5e2e\u52a9\u4e2d\u5fc3\",\"description\":\"\u9999\u6e2f\u670d\u52a1\u5668_\u9999\u6e2f\u4e91\u670d\u52a1\u5668\u8d44\u8baf_\u670d\u52a1\u5668\u5e2e\u52a9\u6587\u6863_\u670d\u52a1\u5668\u6559\u7a0b\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.wsisp.com\/helps\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-Hans\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kubernetes\u822a\u7ebf\u56fe\uff1a\u4ece\u8239\u957f\u5230K8s\u638c\u8235\u8005\u5f52\u6863 - \u7f51\u7855\u4e92\u8054\u5e2e\u52a9\u4e2d\u5fc3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wsisp.com\/helps\/tag\/kubernetes\u822a\u7ebf\u56fe\uff1a\u4ece\u8239\u957f\u5230k8s\u638c\u8235\u8005","og_locale":"zh_CN","og_type":"article","og_title":"Kubernetes\u822a\u7ebf\u56fe\uff1a\u4ece\u8239\u957f\u5230K8s\u638c\u8235\u8005\u5f52\u6863 - \u7f51\u7855\u4e92\u8054\u5e2e\u52a9\u4e2d\u5fc3","og_url":"https:\/\/www.wsisp.com\/helps\/tag\/kubernetes\u822a\u7ebf\u56fe\uff1a\u4ece\u8239\u957f\u5230k8s\u638c\u8235\u8005","og_site_name":"\u7f51\u7855\u4e92\u8054\u5e2e\u52a9\u4e2d\u5fc3","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.wsisp.com\/helps\/tag\/kubernetes%e8%88%aa%e7%ba%bf%e5%9b%be%ef%bc%9a%e4%bb%8e%e8%88%b9%e9%95%bf%e5%88%b0k8s%e6%8e%8c%e8%88%b5%e8%80%85","url":"https:\/\/www.wsisp.com\/helps\/tag\/kubernetes%e8%88%aa%e7%ba%bf%e5%9b%be%ef%bc%9a%e4%bb%8e%e8%88%b9%e9%95%bf%e5%88%b0k8s%e6%8e%8c%e8%88%b5%e8%80%85","name":"Kubernetes\u822a\u7ebf\u56fe\uff1a\u4ece\u8239\u957f\u5230K8s\u638c\u8235\u8005\u5f52\u6863 - \u7f51\u7855\u4e92\u8054\u5e2e\u52a9\u4e2d\u5fc3","isPartOf":{"@id":"https:\/\/www.wsisp.com\/helps\/#website"},"breadcrumb":{"@id":"https:\/\/www.wsisp.com\/helps\/tag\/kubernetes%e8%88%aa%e7%ba%bf%e5%9b%be%ef%bc%9a%e4%bb%8e%e8%88%b9%e9%95%bf%e5%88%b0k8s%e6%8e%8c%e8%88%b5%e8%80%85#breadcrumb"},"inLanguage":"zh-Hans"},{"@type":"BreadcrumbList","@id":"https:\/\/www.wsisp.com\/helps\/tag\/kubernetes%e8%88%aa%e7%ba%bf%e5%9b%be%ef%bc%9a%e4%bb%8e%e8%88%b9%e9%95%bf%e5%88%b0k8s%e6%8e%8c%e8%88%b5%e8%80%85#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.wsisp.com\/helps"},{"@type":"ListItem","position":2,"name":"Kubernetes\u822a\u7ebf\u56fe\uff1a\u4ece\u8239\u957f\u5230K8s\u638c\u8235\u8005"}]},{"@type":"WebSite","@id":"https:\/\/www.wsisp.com\/helps\/#website","url":"https:\/\/www.wsisp.com\/helps\/","name":"\u7f51\u7855\u4e92\u8054\u5e2e\u52a9\u4e2d\u5fc3","description":"\u9999\u6e2f\u670d\u52a1\u5668_\u9999\u6e2f\u4e91\u670d\u52a1\u5668\u8d44\u8baf_\u670d\u52a1\u5668\u5e2e\u52a9\u6587\u6863_\u670d\u52a1\u5668\u6559\u7a0b","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wsisp.com\/helps\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-Hans"}]}},"_links":{"self":[{"href":"https:\/\/www.wsisp.com\/helps\/wp-json\/wp\/v2\/tags\/2396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wsisp.com\/helps\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.wsisp.com\/helps\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.wsisp.com\/helps\/wp-json\/wp\/v2\/posts?tags=2396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}